{"id":4,"count":5,"description":"","link":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/","name":"Parking Lot Sales","slug":"parking-lot-sales","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parking Lot Sales Archives - Collectors Corner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parking Lot Sales Archives - Collectors Corner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/\" \/>\n<meta property=\"og:site_name\" content=\"Collectors Corner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/category\\\/parking-lot-sales\\\/\",\"url\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/category\\\/parking-lot-sales\\\/\",\"name\":\"Parking Lot Sales Archives - Collectors Corner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/category\\\/parking-lot-sales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/category\\\/parking-lot-sales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parking Lot Sales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#website\",\"url\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/\",\"name\":\"Collectors Corner\",\"description\":\"Meadview&#039;s Gift Shop -- Arts and Crafts, Antiques and Collectors&#039; Items\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parking Lot Sales Archives - Collectors Corner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/","og_locale":"en_US","og_type":"article","og_title":"Parking Lot Sales Archives - Collectors Corner","og_url":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/","og_site_name":"Collectors Corner","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/","url":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/","name":"Parking Lot Sales Archives - Collectors Corner","isPartOf":{"@id":"https:\/\/highdesertdirt.com\/collectors\/#website"},"breadcrumb":{"@id":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/highdesertdirt.com\/collectors\/category\/parking-lot-sales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/highdesertdirt.com\/collectors\/"},{"@type":"ListItem","position":2,"name":"Parking Lot Sales"}]},{"@type":"WebSite","@id":"https:\/\/highdesertdirt.com\/collectors\/#website","url":"https:\/\/highdesertdirt.com\/collectors\/","name":"Collectors Corner","description":"Meadview&#039;s Gift Shop -- Arts and Crafts, Antiques and Collectors&#039; Items","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highdesertdirt.com\/collectors\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}