{"id":117,"date":"2017-02-12T07:23:59","date_gmt":"2017-02-12T07:23:59","guid":{"rendered":"http:\/\/highdesertdirt.com\/collectors\/?p=117"},"modified":"2017-03-18T05:50:06","modified_gmt":"2017-03-18T05:50:06","slug":"knife-sharpening-at-the-collectors-corner","status":"publish","type":"post","link":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/","title":{"rendered":"Knife sharpening at the Collectors Corner"},"content":{"rendered":"<p>In the future we&#8217;ll try to let you know ahead of time when Keith sets up.<\/p>\n<p>Keith set up today:<\/p>\n<figure id=\"attachment_119\" aria-describedby=\"caption-attachment-119\" style=\"width: 874px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-119\" src=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg\" alt=\"Knife sharpening\" width=\"874\" height=\"252\" srcset=\"https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg 874w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening-300x86.jpg 300w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening-768x221.jpg 768w\" sizes=\"auto, (max-width: 874px) 100vw, 874px\" \/><\/a><figcaption id=\"caption-attachment-119\" class=\"wp-caption-text\">Knife sharpening<\/figcaption><\/figure>\n<figure id=\"attachment_118\" aria-describedby=\"caption-attachment-118\" style=\"width: 3384px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-118\" src=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes.jpg\" alt=\"Axe sharpening\" width=\"3384\" height=\"2621\" srcset=\"https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes.jpg 3384w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes-300x232.jpg 300w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes-768x595.jpg 768w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/axes-1024x793.jpg 1024w\" sizes=\"auto, (max-width: 3384px) 100vw, 3384px\" \/><\/a><figcaption id=\"caption-attachment-118\" class=\"wp-caption-text\">Ax sharpening<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_120\" aria-describedby=\"caption-attachment-120\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/sharpener.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-120\" src=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/sharpener.jpg\" alt=\"3 stones and cooking oil\" width=\"900\" height=\"426\" srcset=\"https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/sharpener.jpg 900w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/sharpener-300x142.jpg 300w, https:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/sharpener-768x364.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><figcaption id=\"caption-attachment-120\" class=\"wp-caption-text\">3 stones and cooking oil<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In the future we&#8217;ll try to let you know ahead of time when Keith sets up. Keith set up today: &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-117","post","type-post","status-publish","format-standard","hentry","category-knife-sharpening"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Knife sharpening at the Collectors Corner - Collectors Corner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Knife sharpening at the Collectors Corner - Collectors Corner\" \/>\n<meta property=\"og:description\" content=\"In the future we&#8217;ll try to let you know ahead of time when Keith sets up. Keith set up today: &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/\" \/>\n<meta property=\"og:site_name\" content=\"Collectors Corner\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-12T07:23:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-18T05:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg\" \/>\n<meta name=\"author\" content=\"Christine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/\"},\"author\":{\"name\":\"Christine\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#\\\/schema\\\/person\\\/209ad6075ed6745742e4d627035ba093\"},\"headline\":\"Knife sharpening at the Collectors Corner\",\"datePublished\":\"2017-02-12T07:23:59+00:00\",\"dateModified\":\"2017-03-18T05:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/\"},\"wordCount\":57,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/highdesertdirt.com\\\/collectors\\\/files\\\/2017\\\/02\\\/knife-sharpening.jpg\",\"articleSection\":[\"Knife sharpening\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/\",\"url\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/\",\"name\":\"Knife sharpening at the Collectors Corner - Collectors Corner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/highdesertdirt.com\\\/collectors\\\/files\\\/2017\\\/02\\\/knife-sharpening.jpg\",\"datePublished\":\"2017-02-12T07:23:59+00:00\",\"dateModified\":\"2017-03-18T05:50:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#\\\/schema\\\/person\\\/209ad6075ed6745742e4d627035ba093\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#primaryimage\",\"url\":\"http:\\\/\\\/highdesertdirt.com\\\/collectors\\\/files\\\/2017\\\/02\\\/knife-sharpening.jpg\",\"contentUrl\":\"http:\\\/\\\/highdesertdirt.com\\\/collectors\\\/files\\\/2017\\\/02\\\/knife-sharpening.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/2017\\\/02\\\/12\\\/knife-sharpening-at-the-collectors-corner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Knife sharpening at the Collectors Corner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#website\",\"url\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/\",\"name\":\"Collectors Corner\",\"description\":\"Meadview&#039;s Gift Shop -- Arts and Crafts, Antiques and Collectors&#039; Items\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/#\\\/schema\\\/person\\\/209ad6075ed6745742e4d627035ba093\",\"name\":\"Christine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g\",\"caption\":\"Christine\"},\"sameAs\":[\"http:\\\/\\\/highdesertpermaculture.org\"],\"url\":\"https:\\\/\\\/highdesertdirt.com\\\/collectors\\\/author\\\/christine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Knife sharpening at the Collectors Corner - Collectors Corner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/","og_locale":"en_US","og_type":"article","og_title":"Knife sharpening at the Collectors Corner - Collectors Corner","og_description":"In the future we&#8217;ll try to let you know ahead of time when Keith sets up. Keith set up today: &nbsp;","og_url":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/","og_site_name":"Collectors Corner","article_published_time":"2017-02-12T07:23:59+00:00","article_modified_time":"2017-03-18T05:50:06+00:00","og_image":[{"url":"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg","type":"","width":"","height":""}],"author":"Christine","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christine"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#article","isPartOf":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/"},"author":{"name":"Christine","@id":"https:\/\/highdesertdirt.com\/collectors\/#\/schema\/person\/209ad6075ed6745742e4d627035ba093"},"headline":"Knife sharpening at the Collectors Corner","datePublished":"2017-02-12T07:23:59+00:00","dateModified":"2017-03-18T05:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/"},"wordCount":57,"commentCount":0,"image":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#primaryimage"},"thumbnailUrl":"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg","articleSection":["Knife sharpening"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/","url":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/","name":"Knife sharpening at the Collectors Corner - Collectors Corner","isPartOf":{"@id":"https:\/\/highdesertdirt.com\/collectors\/#website"},"primaryImageOfPage":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#primaryimage"},"image":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#primaryimage"},"thumbnailUrl":"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg","datePublished":"2017-02-12T07:23:59+00:00","dateModified":"2017-03-18T05:50:06+00:00","author":{"@id":"https:\/\/highdesertdirt.com\/collectors\/#\/schema\/person\/209ad6075ed6745742e4d627035ba093"},"breadcrumb":{"@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#primaryimage","url":"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg","contentUrl":"http:\/\/highdesertdirt.com\/collectors\/files\/2017\/02\/knife-sharpening.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/highdesertdirt.com\/collectors\/2017\/02\/12\/knife-sharpening-at-the-collectors-corner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/highdesertdirt.com\/collectors\/"},{"@type":"ListItem","position":2,"name":"Knife sharpening at the Collectors Corner"}]},{"@type":"WebSite","@id":"https:\/\/highdesertdirt.com\/collectors\/#website","url":"https:\/\/highdesertdirt.com\/collectors\/","name":"Collectors Corner","description":"Meadview&#039;s Gift Shop -- Arts and Crafts, Antiques and Collectors&#039; Items","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highdesertdirt.com\/collectors\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/highdesertdirt.com\/collectors\/#\/schema\/person\/209ad6075ed6745742e4d627035ba093","name":"Christine","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9490e168bbd452172785149f94c36f589736acfaf570b1af3812a515a5b402?s=96&d=mm&r=g","caption":"Christine"},"sameAs":["http:\/\/highdesertpermaculture.org"],"url":"https:\/\/highdesertdirt.com\/collectors\/author\/christine\/"}]}},"_links":{"self":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":4,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"predecessor-version":[{"id":124,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/posts\/117\/revisions\/124"}],"wp:attachment":[{"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/highdesertdirt.com\/collectors\/wp-json\/wp\/v2\/tags?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}